{"id":15,"date":"2025-06-28T12:40:31","date_gmt":"2025-06-28T12:40:31","guid":{"rendered":"https:\/\/www.designsbylb.com\/contact\/"},"modified":"2025-12-13T09:09:17","modified_gmt":"2025-12-13T09:09:17","slug":"contact","status":"publish","type":"page","link":"https:\/\/www.designsbylb.com\/nl\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<div class=\"contact\">\r\n    <div class=\"contact__inner\">\r\n                <h2 class=\"contact__title\">\r\n            Neem contact op        <\/h2>\r\n        \r\n        <p class=\"contact__text\">\r\n            <i class=\"fa-solid fa-phone contact__icon--phone\"><\/i>\r\n            &nbsp; | &nbsp;\r\n            <i class=\"fa-solid fa-envelope contact__icon--envelope\"><\/i>\r\n        <\/p>\r\n\r\n        <!-- Contact form 7 output -->\r\n        <div class=\"contact__form contact__form--cf7\">\r\n            \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f422-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"422\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/nl\/wp-json\/wp\/v2\/pages\/15#wpcf7-f422-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/nl\/wp-json\/wp\/v2\/pages\/15#wpcf7-f422-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"422\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.4\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f422-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"contact__form\">\n\t<div class=\"contact__hp\" aria-hidden=\"true\">\n\t\t<p><label>Leave this field empty<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"website\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" tabindex=\"-1\" autocomplete=\"off\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"website\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"contact__row\">\n\t\t<p><label for=\"c-name\">Naam<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"c-name\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"contact__row\">\n\t\t<p><label for=\"c-phone\">Telefoon<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" id=\"c-phone\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"your-phone\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"contact__row\">\n\t\t<p><label for=\"c-email\">Email<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" id=\"c-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"contact__row\">\n\t\t<p><label for=\"c-subject\">Subject<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" id=\"c-subject\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"contact__row\">\n\t\t<p><label for=\"c-msg\">Bericht<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"5\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" id=\"c-msg\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<p><button class=\"contact__btn\" type=\"submit\">Verstuur<\/button>\n\t<\/p>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"141\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"nl\"\/><\/form>\n<\/div>\n        <\/div>\r\n\r\n        <img class=\"bnyu-icon contact__bnyu\" src=\"https:\/\/www.designsbylb.com\/wp-content\/themes\/designsbylb\/images\/transparant-bunny.png\"\r\n            alt=\"Rabbit vector\" width=\"20\" height=\"20\" loading=\"lazy\" decoding=\"async\">\r\n    <\/div>\r\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"no-title","meta":{"footnotes":""},"class_list":["post-15","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.designsbylb.com\/nl\/wp-json\/wp\/v2\/pages\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.designsbylb.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.designsbylb.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.designsbylb.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.designsbylb.com\/nl\/wp-json\/wp\/v2\/comments?post=15"}],"version-history":[{"count":2,"href":"https:\/\/www.designsbylb.com\/nl\/wp-json\/wp\/v2\/pages\/15\/revisions"}],"predecessor-version":[{"id":68,"href":"https:\/\/www.designsbylb.com\/nl\/wp-json\/wp\/v2\/pages\/15\/revisions\/68"}],"wp:attachment":[{"href":"https:\/\/www.designsbylb.com\/nl\/wp-json\/wp\/v2\/media?parent=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}